{"id":3484,"date":"2025-10-13T16:04:16","date_gmt":"2025-10-13T14:04:16","guid":{"rendered":"https:\/\/aejf.asso.fr\/?p=3484"},"modified":"2025-10-13T16:09:55","modified_gmt":"2025-10-13T14:09:55","slug":"mcjp%e6%97%a5%e6%9c%ac%e8%aa%9e%e5%a4%9a%e8%aa%ad%e3%82%b5%e3%83%ad%e3%83%b3%e5%87%ba%e5%89%8d%e5%85%88%e6%a9%9f%e9%96%a2%e3%82%92%e5%8b%9f%e9%9b%86%e3%81%97%e3%81%a6%e3%81%84%e3%81%be%e3%81%99","status":"publish","type":"post","link":"https:\/\/aejf.asso.fr\/fr\/related-institutional-information\/projects\/mcjp%e6%97%a5%e6%9c%ac%e8%aa%9e%e5%a4%9a%e8%aa%ad%e3%82%b5%e3%83%ad%e3%83%b3%e5%87%ba%e5%89%8d%e5%85%88%e6%a9%9f%e9%96%a2%e3%82%92%e5%8b%9f%e9%9b%86%e3%81%97%e3%81%a6%e3%81%84%e3%81%be%e3%81%99","title":{"rendered":"[MCJP]Appel \u00e0 candidatures au salon de lecture tadoku en livraison !"},"content":{"rendered":"\n<p>Bonjour \u00e0 toutes et \u00e0 tous,<\/p>\n\n\n\n<p>Nous vous souhaitons une excellente rentr\u00e9e 2025-2026.<\/p>\n\n\n\n<p>Voici quelques informations sur l&rsquo;un des projets de la MCJP projet susceptible de vous int\u00e9resser.<\/p>\n\n\n\n<p>La section de langue japonaise de la MCJP organise dans les \u00e9tablissements d\u2019enseignement de japonais de France m\u00e9tropolitaine int\u00e9ress\u00e9s une activit\u00e9 de lecture <em>tadoku <\/em>itin\u00e9rante, le \u00ab salon de lecture <em>tadoku <\/em>en livraison&nbsp;\u00bb. Nous recherchons actuellement des \u00e9tablissements souhaitant accueillir ce salon entre octobre 2025 et juin 2026.<\/p>\n\n\n\n<p>Dans une activit\u00e9 de lecture <em>tadoku<\/em>, les apprenants\u2026<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\u2705\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/2705\/72.png\">&nbsp;\u2026lisent \u00e0 leur rythme<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\u2705\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/2705\/72.png\">&nbsp;\u2026des livres correspondant \u00e0 leurs int\u00e9r\u00eats<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\u2705\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/2705\/72.png\">&nbsp;\u2026et \u00e0 leur niveau.<\/p>\n\n\n\n<p>Si un livre qu\u2019ils ont choisi ne les int\u00e9resse finalement pas ou s\u2019av\u00e8re trop difficile, il leur suffit de le reposer et d\u2019en choisir un autre.<\/p>\n\n\n\n<p>Le salon de lecture <em>tadoku <\/em>en livraison de la MCJP&#8230;<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\ud83d\udcda\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/1f4da\/72.png\">&nbsp;\u2026est anim\u00e9 par l\u2019\u00e9quipe de la MCJP et dure 1 \u00e0 2 heures (modulable selon les besoins).<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\ud83d\udcda\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/1f4da\/72.png\">&nbsp;\u2026est ouvert \u00e0 tous les types d&rsquo;\u00e9tablissements d&rsquo;enseignement (\u00e9coles primaires, coll\u00e8ges, lyc\u00e9es, universit\u00e9s, \u00e9coles compl\u00e9mentaires, \u00e9coles de langues, etc.).<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\ud83d\udcda\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/1f4da\/72.png\">&nbsp;\u2026est accessible \u00e0 tous les apprenants, quel que soit leur niveau, \u00e0 condition qu&rsquo;ils sachent lire les <em>hiragana.<\/em><\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\ud83d\udcda\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/1f4da\/72.png\">&nbsp;\u2026est gratuit.<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\ud83d\udcda\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/16.0\/1f4da\/72.png\">&nbsp;\u2026peut se d\u00e9placer dans toute la France (et peut aussi s\u2019organiser en ligne).<\/p>\n\n\n\n<p>Pourquoi ne pas organiser un salon de lecture <em>tadoku <\/em>dans votre \u00e9tablissement ?<\/p>\n\n\n\n<p>Pour vous inscrire, rendez-vous sur :<\/p>\n\n\n\n<p><a href=\"https:\/\/forms.office.com\/r\/f7eKLp51yT\">\u00ab\u00a0Salon de lecture MCJP, en livraison !\u00a0\u00bb<\/a><\/p>\n\n\n\n<p>\u203b&nbsp;Apr\u00e8s r\u00e9ception de votre demande, nous vous contacterons pour convenir d&rsquo;une date de visite.<\/p>\n\n\n\n<p>\u203b&nbsp;Les demandes doivent \u00eatre effectu\u00e9es par un enseignant ou un repr\u00e9sentant de l&rsquo;\u00e9tablissement (les demandes \u00e9manant d&rsquo;apprenants ne sont pas accept\u00e9es).<\/p>\n\n\n\n<p>Excellente continuation \u00e0 tous !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Maison de la culture du Japon&nbsp;\u00e0 Paris<\/p>\n\n\n\n<p>Section de langue japonaise<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 toutes et \u00e0 tous, Nous vous souhaitons une excellente rentr\u00e9e 2025-2026. Voici quelques informations [&hellip;]<\/p>\n","protected":false},"author":317,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_locale":"fr_FR","_original_post":"https:\/\/aejf.asso.fr\/?p=3482","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[37,38],"tags":[],"class_list":["post-3484","post","type-post","status-publish","format-standard","hentry","category-projects","category-enseignement-secondaire","fr-FR"],"_links":{"self":[{"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/posts\/3484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/users\/317"}],"replies":[{"embeddable":true,"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/comments?post=3484"}],"version-history":[{"count":3,"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/posts\/3484\/revisions"}],"predecessor-version":[{"id":3490,"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/posts\/3484\/revisions\/3490"}],"wp:attachment":[{"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/media?parent=3484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/categories?post=3484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aejf.asso.fr\/wp-json\/wp\/v2\/tags?post=3484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}